{"id":121,"count":1,"description":"","link":"https:\/\/deeva.website\/product-category\/eau-de-parfum-enfant\/","name":"Eau de parfum Enfant","slug":"eau-de-parfum-enfant","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/deeva.website\/fr-tn\/wp-json\/wp\/v2\/product_cat\/121"}],"collection":[{"href":"https:\/\/deeva.website\/fr-tn\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/deeva.website\/fr-tn\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/deeva.website\/fr-tn\/wp-json\/wp\/v2\/product?product_cat=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}